{"id":51,"count":2,"description":"","link":"https:\/\/mindalcove.com\/blog\/tag\/meditate\/","name":"Meditate","slug":"meditate","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Meditate Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mindalcove.com\/blog\/tag\/meditate\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meditate Archives -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mindalcove.com\/blog\/tag\/meditate\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/mindalcove.com\/blog\/tag\/meditate\/\",\"url\":\"https:\/\/mindalcove.com\/blog\/tag\/meditate\/\",\"name\":\"Meditate Archives -\",\"isPartOf\":{\"@id\":\"https:\/\/mindalcove.com\/blog\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mindalcove.com\/blog\/#website\",\"url\":\"https:\/\/mindalcove.com\/blog\/\",\"name\":\"\",\"description\":\"Mind Alcove Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mindalcove.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meditate Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mindalcove.com\/blog\/tag\/meditate\/","og_locale":"en_US","og_type":"article","og_title":"Meditate Archives -","og_url":"https:\/\/mindalcove.com\/blog\/tag\/meditate\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mindalcove.com\/blog\/tag\/meditate\/","url":"https:\/\/mindalcove.com\/blog\/tag\/meditate\/","name":"Meditate Archives -","isPartOf":{"@id":"https:\/\/mindalcove.com\/blog\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/mindalcove.com\/blog\/#website","url":"https:\/\/mindalcove.com\/blog\/","name":"","description":"Mind Alcove Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mindalcove.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mindalcove.com\/blog\/wp-json\/wp\/v2\/tags\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindalcove.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mindalcove.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mindalcove.com\/blog\/wp-json\/wp\/v2\/posts?tags=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}